{"id":284,"count":16,"description":"Emotions, general description, use of emotions","link":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/","name":"Emotions","slug":"emotions","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emotions Archieven - Linda van der Kwast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emotions Archieven - Linda van der Kwast\" \/>\n<meta property=\"og:description\" content=\"Emotions, general description, use of emotions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/\" \/>\n<meta property=\"og:site_name\" content=\"Linda van der Kwast\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@lindavdkwast\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/\",\"url\":\"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/\",\"name\":\"Emotions Archieven - Linda van der Kwast\",\"isPartOf\":{\"@id\":\"https:\/\/lindavanderkwast.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lindavanderkwast.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emotions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lindavanderkwast.com\/#website\",\"url\":\"https:\/\/lindavanderkwast.com\/\",\"name\":\"Linda van der Kwast\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lindavanderkwast.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emotions Archieven - Linda van der Kwast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/","og_locale":"en_GB","og_type":"article","og_title":"Emotions Archieven - Linda van der Kwast","og_description":"Emotions, general description, use of emotions","og_url":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/","og_site_name":"Linda van der Kwast","twitter_card":"summary_large_image","twitter_site":"@lindavdkwast","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/","url":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/","name":"Emotions Archieven - Linda van der Kwast","isPartOf":{"@id":"https:\/\/lindavanderkwast.com\/#website"},"breadcrumb":{"@id":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/lindavanderkwast.com\/en\/category\/emotions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lindavanderkwast.com\/en\/"},{"@type":"ListItem","position":2,"name":"Emotions"}]},{"@type":"WebSite","@id":"https:\/\/lindavanderkwast.com\/#website","url":"https:\/\/lindavanderkwast.com\/","name":"Linda van der Kwast","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lindavanderkwast.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lindavanderkwast.com\/en\/wp-json\/wp\/v2\/categories\/284\/"}],"collection":[{"href":"https:\/\/lindavanderkwast.com\/en\/wp-json\/wp\/v2\/categories\/"}],"about":[{"href":"https:\/\/lindavanderkwast.com\/en\/wp-json\/wp\/v2\/taxonomies\/category\/"}],"wp:post_type":[{"href":"https:\/\/lindavanderkwast.com\/en\/wp-json\/wp\/v2\/posts\/?categories=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}